{"id":63420,"date":"2020-06-08T00:00:00","date_gmt":"2020-06-08T00:00:00","guid":{"rendered":"http:\/\/blog.mozilla.org\/foxtail\/2020\/06\/08\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/"},"modified":"2020-06-08T00:00:00","modified_gmt":"2020-06-08T00:00:00","slug":"so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst","status":"publish","type":"post","link":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/","title":{"rendered":"So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)"},"content":{"rendered":"<p>Das Leben ist voller Unterbrechungen und Ablenkungen. Immer, wenn man sich auf etwas konzentrieren will, meldet sich irgendjemand und will irgendwas von einem. Zum Beispiel: Marketing-Anrufe der Bank w\u00e4hrend man gerade Mittag isst oder ein gutes Buch in der Hand hat.<\/p>\n<p>Im Web ist das manchmal nicht anders.<\/p>\n<p>Gerade wenn man beginnt, sich in einen interessanten Online-Artikel zu vertiefen, schiebt sich eine Push-Nachricht vor die Linse und fragt, ob sie uns Mitteilungen senden darf. Echt jetzt?<\/p>\n<p>Klar l\u00e4sst sich die Mitteilung mit einem Klick auf \u201cNein, danke\u201d beantworten (was die meisten Menschen auch tun), aber diese Sekunde der Ablenkung stresst. Letztes Jahr haben wir herausgefunden, dass ca. 99% dieser Mitteilungen nicht akzeptiert werden. Ca. 48% davon werden aktiv abgelehnt.<\/p>\n<p>Grund genug, um einmal kurz zu erkl\u00e4ren, wie solche nervenden Nachrichten in Firefox automatisch blockiert werden und woran du das erkennst:<\/p>\n<p><b>Erstens:<\/b> Sobald du in Firefox eine Webseite besuchst, die dir eine Mitteilung schicken will, erscheint statt dem gro\u00dfen Pop-Up-Fenster eine kleine Sprechblase in der Adressleiste. Diese wackelt ein bisschen und zeigt dir damit an, dass gerade eine Mitteilung blockiert wurde.<\/p>\n<p><b>Zweitens:<\/b> Jetzt kannst du dich entscheiden: Entweder du ignorierst die Sprechblase und surfst einfach weiter <b>oder<\/b> du erlaubst diese und weitere Nachrichten auf dieser Seite, indem du auf die kleine Sprechblase klickst.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter \" src=\"https:\/\/user-media-prod-cdn.itsre-sumo.mozilla.net\/uploads\/gallery\/images\/2019-10-31-10-44-39-31aa36.png\" width=\"563\" height=\"150\" \/><\/p>\n<p>Sobald du dich entschieden hast, kannst du auch direkt zur\u00fcck zu den neuesten Nachrichten, der Recherche f\u00fcr die Arbeit oder deinem liebsten Cat Content (wie man das halt so macht).<\/p>\n<p>Wenn du dich umentscheidest und doch wieder die Mitteilungen auf dieser Seite empfangen m\u00f6chtest, ist das kein Problem:<\/p>\n<p>Gehe zu Firefox Einstellungen > Datenschutz &#038; Sicherheit > Berechtigungen und klicke dort auf Einstellungen. Dort siehst du alle Seiten, die geblockt sind und kannst sie ganz einfach \u201centblocken\u201d.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full\" src=\"https:\/\/user-media-prod-cdn.itsre-sumo.mozilla.net\/uploads\/gallery\/images\/2018-04-09-16-38-00-823ac0.png\" width=\"738\" height=\"560\" \/><\/p>\n<p>Einige Websites fragen ein zweites Mal nach, nachdem du mit ihnen interagierst hast. Klicke dann auf \u201cneue Mitteilungen blockieren\u201d \u2013 damit bist alle Mitteilungen f\u00fcr immer los!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Leben ist voller Unterbrechungen und Ablenkungen. Immer, wenn man sich auf etwas konzentrieren will, meldet sich irgendjemand und will irgendwas von einem. Zum Beispiel: Marketing-Anrufe der Bank w\u00e4hrend man gerade Mittag isst oder ein gutes Buch in der Hand hat. Im Web ist das manchmal nicht anders. Gerade wenn man beginnt, sich in einen [&hellip;]<\/p>\n","protected":false},"author":727,"featured_media":53001,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,464263,464337,290437],"tags":[313620,326369,451273],"coauthors":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)<\/title>\n<meta name=\"description\" content=\"Keine Lust auf Mitteilungen von Websites? Wir zeigen dir, wie du solche Nachrichten mit Firefox automatisch blockieren kannst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/\",\"url\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/\",\"name\":\"So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)\",\"isPartOf\":{\"@id\":\"https:\/\/blog.mozilla.org\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/blog.mozilla.org\/wp-content\/blogs.dir\/278\/files\/2020\/01\/header_block-notifications.png\",\"datePublished\":\"2020-06-08T00:00:00+00:00\",\"dateModified\":\"2020-06-08T00:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/blog.mozilla.org\/de\/#\/schema\/person\/5c987afc4f606be73692d2acfdd1316c\"},\"description\":\"Keine Lust auf Mitteilungen von Websites? Wir zeigen dir, wie du solche Nachrichten mit Firefox automatisch blockieren kannst.\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#primaryimage\",\"url\":\"https:\/\/blog.mozilla.org\/wp-content\/blogs.dir\/278\/files\/2020\/01\/header_block-notifications.png\",\"contentUrl\":\"https:\/\/blog.mozilla.org\/wp-content\/blogs.dir\/278\/files\/2020\/01\/header_block-notifications.png\",\"width\":1200,\"height\":660},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.mozilla.org\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.mozilla.org\/de\/#website\",\"url\":\"https:\/\/blog.mozilla.org\/de\/\",\"name\":\"The Mozilla Blog\",\"description\":\"News and Updates about Mozilla\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.mozilla.org\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.mozilla.org\/de\/#\/schema\/person\/5c987afc4f606be73692d2acfdd1316c\",\"name\":\"M.J. Kelly\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/blog.mozilla.org\/de\/#\/schema\/person\/image\/70718b02fa9f11d88288b937f1da2ac1\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d61ff6a9eb6dd324df20cb773e6c416e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d61ff6a9eb6dd324df20cb773e6c416e?s=96&d=mm&r=g\",\"caption\":\"M.J. Kelly\"},\"description\":\"Mozilla Communications\",\"url\":\"https:\/\/blog.mozilla.org\/de\/author\/mjkellymozilla-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)","description":"Keine Lust auf Mitteilungen von Websites? Wir zeigen dir, wie du solche Nachrichten mit Firefox automatisch blockieren kannst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/","url":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/","name":"So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)","isPartOf":{"@id":"https:\/\/blog.mozilla.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#primaryimage"},"image":{"@id":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.mozilla.org\/wp-content\/blogs.dir\/278\/files\/2020\/01\/header_block-notifications.png","datePublished":"2020-06-08T00:00:00+00:00","dateModified":"2020-06-08T00:00:00+00:00","author":{"@id":"https:\/\/blog.mozilla.org\/de\/#\/schema\/person\/5c987afc4f606be73692d2acfdd1316c"},"description":"Keine Lust auf Mitteilungen von Websites? Wir zeigen dir, wie du solche Nachrichten mit Firefox automatisch blockieren kannst.","breadcrumb":{"@id":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#primaryimage","url":"https:\/\/blog.mozilla.org\/wp-content\/blogs.dir\/278\/files\/2020\/01\/header_block-notifications.png","contentUrl":"https:\/\/blog.mozilla.org\/wp-content\/blogs.dir\/278\/files\/2020\/01\/header_block-notifications.png","width":1200,"height":660},{"@type":"BreadcrumbList","@id":"https:\/\/blog.mozilla.org\/de\/firefox\/so-stellst-du-nervige-website-mitteilungen-einfach-ab-wenn-du-das-willst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.mozilla.org\/de\/"},{"@type":"ListItem","position":2,"name":"So stellst du nervige Website-Mitteilungen einfach ab (wenn du das willst)"}]},{"@type":"WebSite","@id":"https:\/\/blog.mozilla.org\/de\/#website","url":"https:\/\/blog.mozilla.org\/de\/","name":"The Mozilla Blog","description":"News and Updates about Mozilla","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.mozilla.org\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/blog.mozilla.org\/de\/#\/schema\/person\/5c987afc4f606be73692d2acfdd1316c","name":"M.J. Kelly","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.mozilla.org\/de\/#\/schema\/person\/image\/70718b02fa9f11d88288b937f1da2ac1","url":"https:\/\/secure.gravatar.com\/avatar\/d61ff6a9eb6dd324df20cb773e6c416e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d61ff6a9eb6dd324df20cb773e6c416e?s=96&d=mm&r=g","caption":"M.J. Kelly"},"description":"Mozilla Communications","url":"https:\/\/blog.mozilla.org\/de\/author\/mjkellymozilla-com\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/posts\/63420"}],"collection":[{"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/users\/727"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/comments?post=63420"}],"version-history":[{"count":0,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/posts\/63420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/media\/53001"}],"wp:attachment":[{"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/media?parent=63420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/categories?post=63420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/tags?post=63420"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/blog.mozilla.org\/de\/wp-json\/wp\/v2\/coauthors?post=63420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}