{"id":507,"date":"2013-08-07T09:48:07","date_gmt":"2013-08-07T07:48:07","guid":{"rendered":"http:\/\/blog.mozilla.org\/press-it\/?p=507"},"modified":"2013-08-07T09:48:07","modified_gmt":"2013-08-07T07:48:07","slug":"firefox-23-facilita-la-condivisione-dei-contenuti-preferiti-con-amici-e-familiari","status":"publish","type":"post","link":"https:\/\/blog.mozilla.org\/press-it\/2013\/08\/07\/firefox-23-facilita-la-condivisione-dei-contenuti-preferiti-con-amici-e-familiari\/","title":{"rendered":"Firefox 23 facilita la condivisione dei contenuti preferiti con amici e familiari"},"content":{"rendered":"<p>Siti e servizi social sono ormai una parte fondamentale della vita online: per questo Mozilla sviluppa Firefox andando incontro ai sempre nuovi modi di utilizzare il Web. Nel corso dell&#8217;ultimo anno Mozilla ha studiato il modo di integrare siti e servizi social direttamente in Firefox per connettersi con amici e familiari rapidamente e facilmente.<\/p>\n<p>L&#8217;anno scorso <a href=\"https:\/\/blog.mozilla.org\/blog\/2012\/12\/03\/firefox-gets-social-w-facebook\/\">Facebook \u00e8 stato il primo partner<\/a> di Mozilla nell\u2019integrazione social di Firefox. Poco dopo si sono aggiunti Cliqz, Mixi e msnNOW e la Fondazione fa sapere che presto si aggiungeranno ancora pi\u00f9 siti, servizi e applicazioni per rendere l\u2019esperienza di navigazione pi\u00f9 social, su misura e personalizzabile.<\/p>\n<p>Nell\u2019ottica di espandere l\u2019offerta social per offrire un&#8217;esperienza ancora migliore, Mozilla ha sviluppato la possibilit\u00e0 di condividere facilmente i contenuti da Firefox. Il pulsante Condividi nella barra degli strumenti di Firefox consente di trasmettere i propri contenuti preferiti in pochi clic ad amici o followers direttamente da Firefox, ovunque ci si trovi sul Web. \u00c8 possibile pubblicare un articolo interessante sul proprio profilo, condividere una ricetta con gli amici o inviare un&#8217;idea regalo tramite messaggio privato o e-mail, il tutto senza lasciare la pagina Web che si sta visitando. Questa funzionalit\u00e0 \u00e8 ora disponibile con Facebook Messenger per Firefox o con Cliqz.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/blog.mozilla.org\/press-it\/files\/2013\/08\/Facebook-Screenshot_Firefox23GA.png\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-506\" alt=\"Facebook-Screenshot_Firefox23GA\" src=\"https:\/\/blog.mozilla.org\/press-it\/files\/2013\/08\/Facebook-Screenshot_Firefox23GA.png\" width=\"600\" height=\"319\" srcset=\"https:\/\/blog.mozilla.org\/press-it\/files\/2013\/08\/Facebook-Screenshot_Firefox23GA.png 600w, https:\/\/blog.mozilla.org\/press-it\/files\/2013\/08\/Facebook-Screenshot_Firefox23GA-252x133.png 252w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>Firefox, inoltre, pu\u00f2 essere utilizzato anche in altri modi per interagire con amici e familiari. \u00c8 possibile infatti commentare o vedere i propri contenuti personali tramite una barra laterale apposita, controllare le notifiche direttamente all&#8217;interno della barra degli strumenti di Firefox, chattare senza lasciare la pagina web che si sta visitando e, ora, condividere contenuti con i propri amici, followers e gruppi direttamente all&#8217;interno di Firefox.<br \/>\nNell\u2019esperienza fornita da Firefox c\u2019\u00e8 un potenziale infinito per l&#8217;integrazione di social network, e-mail, notizie finanziarie, musica, to-do list, sport, e altre applicazioni.<\/p>\n<p>Per maggiori informazioni:<\/p>\n<p>* <a href=\"https:\/\/www.mozilla.org\/it\/firefox\/fx\/#desktop\">Download Firefox<\/a> per Windows, Mac e Linux<\/p>\n<p>* <a href=\"http:\/\/www.mozilla.org\/en-US\/firefox\/23.0\/releasenotes\/\">Note di rilascio<\/a> di Firefox per Windows, Mac e Linux<\/p>\n<p>* <a href=\"https:\/\/blog.mozilla.org\/security\/2013\/06\/27\/mixed-content-blocker-hits-firefox-beta\/\">Mixed Content Blocker<\/a><\/p>\n<p>* Il <a href=\"https:\/\/blog.mozilla.org\/creative\/2013\/06\/27\/a-new-firefox-logo-for-a-new-firefox-era\/\">nuovo logo<\/a> di Firefox<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siti e servizi social sono ormai una parte fondamentale della vita online: per questo Mozilla sviluppa Firefox andando incontro ai sempre nuovi modi di utilizzare il Web. Nel corso dell&#8217;ultimo &hellip; <a class=\"go\" href=\"https:\/\/blog.mozilla.org\/press-it\/2013\/08\/07\/firefox-23-facilita-la-condivisione-dei-contenuti-preferiti-con-amici-e-familiari\/\">Read more<\/a><\/p>\n","protected":false},"author":496,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/posts\/507"}],"collection":[{"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/users\/496"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/comments?post=507"}],"version-history":[{"count":0,"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/posts\/507\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/media?parent=507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/categories?post=507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.mozilla.org\/press-it\/wp-json\/wp\/v2\/tags?post=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}