{"id":213,"date":"2009-12-09T11:20:57","date_gmt":"2009-12-09T19:20:57","guid":{"rendered":"http:\/\/blog.mozilla.org\/tomcat\/?p=213"},"modified":"2009-12-09T11:20:57","modified_gmt":"2009-12-09T19:20:57","slug":"open-source-treffen-in-munchen-und-leipzig","status":"publish","type":"post","link":"https:\/\/blog.mozilla.org\/tomcat\/2009\/12\/09\/open-source-treffen-in-munchen-und-leipzig\/","title":{"rendered":"Open-Source-Treffen in M\u00fcnchen und Leipzig!"},"content":{"rendered":"<p>Viele Menschen nutzen heutzutage Open-Source-Software. Fast immer wird diese Software von Ehrenamtlichen in ihrer Freizeit entwickelt, dokumentiert, vermarktet und verbessert. Zahlreiche Open-Source-Projekte arbeiten aktiv daran, den Gedanken freier Software und freier Inhalte voranzubringen, und viele Menschen setzen diese Programme ein und profitieren davon. Anders als bei der meisten propriet\u00e4ren Software, k\u00f6nnen die Nutzer \u00fcber Blogs, IRC-Kan\u00e4le, Mailinglisten und Foren in direkten Kontakt mit den Menschen hinter den Projekten treten.<\/p>\n<p>So sch\u00f6n die moderne Kommunikationswelt auch ist, der pers\u00f6nliche Kontakt ist immer noch am besten. Ein Gesicht zum Namen erleichtert manches, und viele Leute finden durch den pers\u00f6nlichen Kontakt selbst den Weg ins Projekt, um sich dort zu engagieren. Im Rahmen einer Idee m\u00f6chten wir versuchen, die Macher und die Nutzer von freier Software zusammenzubringen \u2013 in gem\u00fctlicher Atmosph\u00e4re, ganz unverbindlich, ohne kommerzielle Hintergedanken. Das ist die Idee der Open-Source-Treffen &#8211; eine Idee von Openoffice.org und Mozilla.<br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-141\" title=\"open source meetup munich logo\" src=\"http:\/\/blog.mozilla.org\/tomcat\/files\/2009\/07\/moewe-300x246.jpg\" alt=\"open source meetup munich logo\" width=\"300\" height=\"246\" srcset=\"https:\/\/blog.mozilla.org\/tomcat\/files\/2009\/07\/moewe-300x246.jpg 300w, https:\/\/blog.mozilla.org\/tomcat\/files\/2009\/07\/moewe.jpg 396w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Ende November hatten wir in M\u00fcnchen unser bereits 4. Open-Source-Treffen und mit ca. 50 Teilnehmern einen neuen Rekord !<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-202\" title=\"welcome\" src=\"http:\/\/blog.mozilla.org\/tomcat\/files\/2009\/11\/moto_0072-225x300.jpg\" alt=\"welcome\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.mozilla.org\/tomcat\/files\/2009\/11\/moto_0072-225x300.jpg 225w, https:\/\/blog.mozilla.org\/tomcat\/files\/2009\/11\/moto_0072.jpg 384w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>Wie bisher auch es 4 Vortr\u00e4ge:<\/p>\n<p>Joel Hatsch \u2013 Cacert<\/p>\n<p>Heinz Graesing vom x2go Projekt ueber <em>x2go<\/em> als Terminalserver<\/p>\n<p><a href=\"http:\/\/www.linux-magazin.de\/Blogs\/floeff\">Florian Effenberger<\/a> \u00fcber die Organisation des Openoffice.org Projects<\/p>\n<p>und ein Vortrag von mir \u00fcber die Mitmachmoeglichkeiten beim Mozilla Projekt und Personas for Firefox !<br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-204\" title=\"picture from the sessions\" src=\"http:\/\/blog.mozilla.org\/tomcat\/files\/2009\/11\/moto_0086-225x300.jpg\" alt=\"picture from the sessions\" width=\"225\" height=\"300\" srcset=\"https:\/\/blog.mozilla.org\/tomcat\/files\/2009\/11\/moto_0086-225x300.jpg 225w, https:\/\/blog.mozilla.org\/tomcat\/files\/2009\/11\/moto_0086.jpg 384w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>Ein sehr erfolgreicher Abend mit vielen interessanten Gespr\u00e4chen und Diskussionen !<\/p>\n<p>Am 23.11 ging es dann nach Leipzig zum 1. Open-Source-Treffen in Leipzig (nochmals vielen Dank an die Leipziger !) und mit ca. 35 G\u00e4sten und 4 Vortr\u00e4gen (DTP auf Linux, OpenStreetmap, Openoffice.org und nat\u00fcrlich Mozilla \ud83d\ude42<\/p>\n<p>Und das waren die Open-Source-Treffen 2009 \ud83d\ude42 und es ist Zeit Danke zu sagen :<\/p>\n<p>Vielen Dank an die engagierte Truppe rund um Marco, Kai und Mathias, die in Leipzig ein Event der Spitzenklasse auf die Beine gestellt haben! Auch den treuen Seelen vom <a href=\"http:\/\/www.cafe-netzwerk.de\/\">M\u00fcnchener Caf\u00e9 Netzwerk<\/a> mit dem Team um Armin ein herzliches Dankesch\u00f6n f\u00fcr die Unterst\u00fctzung, denn ohne euch w\u00e4re die Veranstaltung in der Form nicht m\u00f6glich! Ihr seid spitze!<\/p>\n<p>Jetzt machen wir erstmal eine wohlverdiente Weihnachtspause, um dann voraussichtlich im Januar 2010 wieder voll durchzustarten. In Leipzig soll die Veranstaltung vermutlich im Fr\u00fchjahr wieder stattfinden, in M\u00fcnchen \u00fcberlegen wir schon, auf einen monatlichen Rhythmus umzustellen. Zus\u00e4tzlich werden wir voraussichtlich Ende Februar (am 26.2 \ud83d\ude42  wieder Open-Source-&#8220;Prominenz&#8221; im Caf\u00e9 Netzwerk begr\u00fc\u00dfen d\u00fcrfen, aber mehr wird noch nicht verraten!<\/p>\n<p>Ansonsten  OpenSource Projekte leben vom Mitmachen ! Von daher selbst wenn ihr nur ein paar Minuten Zeit habt, unterst\u00fctzt das Lieblingsprojekt Eurer Wahl z.B. mit dem <a href=\"http:\/\/www.mozilla.com\/en-US\/firefox\/all-beta.html\">Testen von Firefox 3.6<\/a><\/p>\n<p>Sch\u00f6ne Weihnachten und einen Guten Start in das Jahr 2010 \u2013 Open-Source-Meetups will be back !<\/p>\n<p>&#8211; Tomcat<\/p>\n<p>Bilder vom Event von Muenchen gibt es hier : <a href=\"http:\/\/picasaweb.google.de\/carstenbook\/OpenSourceMeetupMunich20November2010\">http:\/\/picasaweb.google.de\/carstenbook\/OpenSourceMeetupMunich20November2010<\/a>#<\/p>\n<p>Slides meiner Vortraege sind hier : <a href=\"http:\/\/www.slideshare.net\/BavarianTomcat\">http:\/\/www.slideshare.net\/BavarianTomcat<\/a><\/p>\n<p>Open-Source-Treffen Webseite: <a href=\"http:\/\/www.opensourcetreffen.de\/\">http:\/\/www.opensourcetreffen.de\/<\/a><\/p>\n<p>Facebook Gruppe: <a href=\"http:\/\/www.facebook.com\/group.php?gid=211377208975\">http:\/\/www.facebook.com\/group.php?gid=211377208975<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viele Menschen nutzen heutzutage Open-Source-Software. Fast immer wird diese Software von Ehrenamtlichen in ihrer Freizeit entwickelt, dokumentiert, vermarktet und verbessert. Zahlreiche Open-Source-Projekte arbeiten aktiv daran, den Gedanken freier Software und freier Inhalte voranzubringen, und viele Menschen setzen diese Programme ein und profitieren davon. Anders als bei der meisten propriet\u00e4ren Software, k\u00f6nnen die Nutzer \u00fcber Blogs, [&hellip;]<\/p>\n","protected":false},"author":82,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[648],"tags":[],"_links":{"self":[{"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/posts\/213"}],"collection":[{"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/users\/82"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/comments?post=213"}],"version-history":[{"count":0,"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/posts\/213\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/media?parent=213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/categories?post=213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.mozilla.org\/tomcat\/wp-json\/wp\/v2\/tags?post=213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}